{"id":106,"count":1,"description":"","link":"https:\/\/www.sosciso.de\/en\/tag\/key-firefox\/","name":"Firefox","slug":"key-firefox","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Firefox Archives - Social Science Software<\/title>\n<meta name=\"description\" content=\"Social Science Software liefert eine vollst\u00e4ndige \u00dcbersicht \u00fcber die Software, welche im sozialwissenschaftlichen Forschungsprozess eingesetzt werden kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sosciso.de\/de\/tag\/key-firefox\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.sosciso.de\/de\/tag\/key-firefox\/\",\"url\":\"https:\/\/www.sosciso.de\/de\/tag\/key-firefox\/\",\"name\":\"Firefox Archives - Social Science Software\",\"isPartOf\":{\"@id\":\"https:\/\/www.sosciso.de\/en\/#website\"},\"description\":\"Social Science Software liefert eine vollst\u00e4ndige \u00dcbersicht \u00fcber die Software, welche im sozialwissenschaftlichen Forschungsprozess eingesetzt werden kann.\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sosciso.de\/en\/#website\",\"url\":\"https:\/\/www.sosciso.de\/en\/\",\"name\":\"Social Science Software\",\"description\":\"Software in Social Science Research\",\"publisher\":{\"@id\":\"https:\/\/www.sosciso.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sosciso.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sosciso.de\/en\/#organization\",\"name\":\"Social Science Software\",\"url\":\"https:\/\/www.sosciso.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.sosciso.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sosciso.de\/wp-content\/uploads\/2021\/01\/logo_weiss_3434.png\",\"contentUrl\":\"https:\/\/www.sosciso.de\/wp-content\/uploads\/2021\/01\/logo_weiss_3434.png\",\"width\":34,\"height\":34,\"caption\":\"Social Science Software\"},\"image\":{\"@id\":\"https:\/\/www.sosciso.de\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Firefox Archives - Social Science Software","description":"Social Science Software liefert eine vollst\u00e4ndige \u00dcbersicht \u00fcber die Software, welche im sozialwissenschaftlichen Forschungsprozess eingesetzt werden kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sosciso.de\/de\/tag\/key-firefox\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.sosciso.de\/de\/tag\/key-firefox\/","url":"https:\/\/www.sosciso.de\/de\/tag\/key-firefox\/","name":"Firefox Archives - Social Science Software","isPartOf":{"@id":"https:\/\/www.sosciso.de\/en\/#website"},"description":"Social Science Software liefert eine vollst\u00e4ndige \u00dcbersicht \u00fcber die Software, welche im sozialwissenschaftlichen Forschungsprozess eingesetzt werden kann.","inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.sosciso.de\/en\/#website","url":"https:\/\/www.sosciso.de\/en\/","name":"Social Science Software","description":"Software in Social Science Research","publisher":{"@id":"https:\/\/www.sosciso.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sosciso.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sosciso.de\/en\/#organization","name":"Social Science Software","url":"https:\/\/www.sosciso.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sosciso.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sosciso.de\/wp-content\/uploads\/2021\/01\/logo_weiss_3434.png","contentUrl":"https:\/\/www.sosciso.de\/wp-content\/uploads\/2021\/01\/logo_weiss_3434.png","width":34,"height":34,"caption":"Social Science Software"},"image":{"@id":"https:\/\/www.sosciso.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sosciso.de\/en\/wp-json\/wp\/v2\/tags\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sosciso.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sosciso.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sosciso.de\/en\/wp-json\/wp\/v2\/posts?tags=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}